{"id":331,"count":8,"description":"","link":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/","name":"Sale conferenze","slug":"sale-conferenze","taxonomy":"portfolio_entries","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pannelli fonoassorbenti per sale conferenze | LvB Italia<\/title>\n<meta name=\"description\" content=\"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pannelli fonoassorbenti per sale conferenze | LvB Italia\" \/>\n<meta property=\"og:description\" content=\"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Pannelli fonoassorbenti design\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/\",\"name\":\"Pannelli fonoassorbenti per sale conferenze | LvB Italia\",\"isPartOf\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#website\"},\"description\":\"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lvbitalia.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sale conferenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#website\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/\",\"name\":\"Pannelli fonoassorbenti design\",\"description\":\"PHONODESIGN Made in Italy\",\"publisher\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lvbitalia.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#organization\",\"name\":\"LvB Italia\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png\",\"contentUrl\":\"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png\",\"width\":314,\"height\":160,\"caption\":\"LvB Italia\"},\"image\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pannelli fonoassorbenti per sale conferenze | LvB Italia","description":"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/","og_locale":"it_IT","og_type":"article","og_title":"Pannelli fonoassorbenti per sale conferenze | LvB Italia","og_description":"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.","og_url":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/","og_site_name":"Pannelli fonoassorbenti design","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/","url":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/","name":"Pannelli fonoassorbenti per sale conferenze | LvB Italia","isPartOf":{"@id":"https:\/\/www.lvbitalia.com\/it\/#website"},"description":"Sale conferenze \u27a4 Migliora l\u2019acustica e riduci il riverbero con pannelli fonoassorbenti su misura \u2713Comfort sonoro e design elegante per ogni ambiente.","breadcrumb":{"@id":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lvbitalia.com\/it\/sale-conferenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lvbitalia.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sale conferenze"}]},{"@type":"WebSite","@id":"https:\/\/www.lvbitalia.com\/it\/#website","url":"https:\/\/www.lvbitalia.com\/it\/","name":"Pannelli fonoassorbenti design","description":"PHONODESIGN Made in Italy","publisher":{"@id":"https:\/\/www.lvbitalia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lvbitalia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.lvbitalia.com\/it\/#organization","name":"LvB Italia","url":"https:\/\/www.lvbitalia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png","contentUrl":"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png","width":314,"height":160,"caption":"LvB Italia"},"image":{"@id":"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/portfolio_entries\/331"}],"collection":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/portfolio_entries"}],"about":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/taxonomies\/portfolio_entries"}],"wp:post_type":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/portfolio?portfolio_entries=331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}