{"id":35,"count":0,"description":"","link":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/","name":"Hand made","slug":"hand-made","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design<\/title>\n<meta name=\"description\" content=\"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design\" \/>\n<meta property=\"og:description\" content=\"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/\" \/>\n<meta property=\"og:site_name\" content=\"Pannelli fonoassorbenti design\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/\",\"name\":\"Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design\",\"isPartOf\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#website\"},\"description\":\"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lvbitalia.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hand made\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#website\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/\",\"name\":\"Pannelli fonoassorbenti design\",\"description\":\"PHONODESIGN Made in Italy\",\"publisher\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lvbitalia.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#organization\",\"name\":\"LvB Italia\",\"url\":\"https:\/\/www.lvbitalia.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png\",\"contentUrl\":\"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png\",\"width\":314,\"height\":160,\"caption\":\"LvB Italia\"},\"image\":{\"@id\":\"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design","description":"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design","og_description":"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!","og_url":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/","og_site_name":"Pannelli fonoassorbenti design","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/","url":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/","name":"Pannelli fonoassorbenti fatti a mano | Pannelli fonoassorbenti design","isPartOf":{"@id":"https:\/\/www.lvbitalia.com\/it\/#website"},"description":"Pannelli acustici fatti a mano \u27a4 Scopri i nostri pannelli fonoassorbenti fatti a mano e personalizzati \u2713Contattaci per una consulenza gratuita sul tuo progetto!","breadcrumb":{"@id":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lvbitalia.com\/it\/tag\/hand-made\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lvbitalia.com\/it\/"},{"@type":"ListItem","position":2,"name":"Hand made"}]},{"@type":"WebSite","@id":"https:\/\/www.lvbitalia.com\/it\/#website","url":"https:\/\/www.lvbitalia.com\/it\/","name":"Pannelli fonoassorbenti design","description":"PHONODESIGN Made in Italy","publisher":{"@id":"https:\/\/www.lvbitalia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lvbitalia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.lvbitalia.com\/it\/#organization","name":"LvB Italia","url":"https:\/\/www.lvbitalia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png","contentUrl":"https:\/\/www.lvbitalia.com\/wp-content\/uploads\/2022\/05\/logo-lvb-nero.png","width":314,"height":160,"caption":"LvB Italia"},"image":{"@id":"https:\/\/www.lvbitalia.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/tags\/35"}],"collection":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/posts?tags=35"},{"href":"https:\/\/www.lvbitalia.com\/it\/wp-json\/wp\/v2\/portfolio?tags=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}